{"id":828,"count":9,"description":"<img decoding=async data-opt-id=969926837  fetchpriority=\"high\" class=\"alignnone wp-image-17663 size-full\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch_en-3.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nInject hair with intense colour! Croma Touch is the new instant colour system specifically created by Technique to revive and brighten your look with 9 exquisite nuances: more pigments for richer colour tones, intense nourishment and a balanced colour result.","link":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/","name":"Croma Touch","slug":"croma-touch-en","taxonomy":"product_cat","parent":826,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maschera a colorazione diretta in 9 nuance Croma Touch<\/title>\n<meta name=\"description\" content=\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maschera a colorazione diretta in 9 nuance Croma Touch\" \/>\n<meta property=\"og:description\" content=\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/colour\\\/croma-touch-en\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/colour\\\/croma-touch-en\\\/\",\"name\":\"Maschera a colorazione diretta in 9 nuance Croma Touch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/#website\"},\"description\":\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/colour\\\/croma-touch-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/colour\\\/croma-touch-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colour\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/colour\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Croma Touch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maschera a colorazione diretta in 9 nuance Croma Touch","description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/","og_locale":"en_US","og_type":"article","og_title":"Maschera a colorazione diretta in 9 nuance Croma Touch","og_description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","og_url":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/","url":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/","name":"Maschera a colorazione diretta in 9 nuance Croma Touch","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/en\/#website"},"description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/croma-touch-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Colour","item":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/colour\/"},{"@type":"ListItem","position":3,"name":"Croma Touch"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/en\/#website","url":"https:\/\/sandbox.technique-italia.com\/en\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat\/826"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product?product_cat=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}