{"id":846,"count":3,"description":"<img decoding=async data-opt-id=1909780553  fetchpriority=\"high\" class=\"wp-image-15659 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_silver_en.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nAlkemy Silver <strong>Shampoo and Mask<\/strong>: revives and brightens white and grey hair, removing unwanted yellow tones.","link":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/","name":"Alkemy Silver","slug":"alkemy-silver-en","taxonomy":"product_cat","parent":841,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati<\/title>\n<meta name=\"description\" content=\"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati\" \/>\n<meta property=\"og:description\" content=\"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_silver_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/treatments\\\/alkemy-silver-en\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/treatments\\\/alkemy-silver-en\\\/\",\"name\":\"Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/#website\"},\"description\":\"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/treatments\\\/alkemy-silver-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/treatments\\\/alkemy-silver-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Treatments\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/categoria-prodotto\\\/treatments\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alkemy Silver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati","description":"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/","og_locale":"en_US","og_type":"article","og_title":"Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati","og_description":"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.","og_url":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_silver_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/","url":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/","name":"Alkemy Silver - Trattamento Antigiallo per Capelli Bianchi e Decolorati","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/en\/#website"},"description":"Inizia una nuova vita per i tuoi capelli con Shampoo e Maschera Alkemy Silver: riaccendi lo splendore dei capelli bianchi, spegnendo i toni gialli indesiderati.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/alkemy-silver-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Treatments","item":"https:\/\/sandbox.technique-italia.com\/en\/categoria-prodotto\/treatments\/"},{"@type":"ListItem","position":3,"name":"Alkemy Silver"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/en\/#website","url":"https:\/\/sandbox.technique-italia.com\/en\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat\/846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product_cat\/841"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/en\/wp-json\/wp\/v2\/product?product_cat=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}