{"id":1048,"count":9,"description":"<img decoding=async data-opt-id=345820439  fetchpriority=\"high\" class=\"wp-image-15858 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_tratamiento_balje_ES.png\" alt=\"\" width=\"1596\" height=\"319\" \/>\r\n\r\nTratamiento completo para una limpieza suave y una revitalizaci\u00f3n completa. Adecuado para cabellos tratados, da\u00f1ados, secos o grasos, Balj\u00e9 ofrece una gama de productos innovadores enriquecidos con ingredientes funcionales y beneficiosos, esenciales para el cuidado del cabello.","link":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/","name":"Balj\u00e9","slug":"balje-es","taxonomy":"product_cat","parent":1041,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trattamento completo per l&#039;hair care Balj\u00e9<\/title>\n<meta name=\"description\" content=\"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trattamento completo per l&#039;hair care Balj\u00e9\" \/>\n<meta property=\"og:description\" content=\"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_balje_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/balje-es\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/balje-es\\\/\",\"name\":\"Trattamento completo per l'hair care Balj\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/#website\"},\"description\":\"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/balje-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/balje-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tratamientos\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Balj\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trattamento completo per l'hair care Balj\u00e9","description":"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/","og_locale":"es_ES","og_type":"article","og_title":"Trattamento completo per l'hair care Balj\u00e9","og_description":"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.","og_url":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_balje_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/","url":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/","name":"Trattamento completo per l'hair care Balj\u00e9","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/es\/#website"},"description":"Balj\u00e9 \u00e8 il trattamento completo per una detersione delicata e una rivitalizzazione completa, indicato per capelli trattati, sfibrati, secchi o grassi.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/balje-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tratamientos","item":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/"},{"@type":"ListItem","position":3,"name":"Balj\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/es\/#website","url":"https:\/\/sandbox.technique-italia.com\/es\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat\/1041"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product?product_cat=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}