{"id":1049,"count":6,"description":"<img decoding=async data-opt-id=1677168778  fetchpriority=\"high\" class=\"wp-image-15628 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_tratamiento_mirylia_ES.png\" alt=\"\" width=\"1596\" height=\"319\" \/>\r\n<p style=\"text-align: left\">Mirylia, tratamiento sublimador del brillo para tu cabello.<\/p>","link":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/","name":"Mirylia","slug":"mirylia-es","taxonomy":"product_cat","parent":1041,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mirylia - Trattamento lucentezza | Technique<\/title>\n<meta name=\"description\" content=\"Mirylia, trattamento sublimatore di lucentezza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mirylia - Trattamento lucentezza | Technique\" \/>\n<meta property=\"og:description\" content=\"Mirylia, trattamento sublimatore di lucentezza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_mirylia_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/mirylia-es\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/mirylia-es\\\/\",\"name\":\"Mirylia - Trattamento lucentezza | Technique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/#website\"},\"description\":\"Mirylia, trattamento sublimatore di lucentezza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/mirylia-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/mirylia-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tratamientos\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/categoria-prodotto\\\/tratamientos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mirylia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mirylia - Trattamento lucentezza | Technique","description":"Mirylia, trattamento sublimatore di lucentezza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/","og_locale":"es_ES","og_type":"article","og_title":"Mirylia - Trattamento lucentezza | Technique","og_description":"Mirylia, trattamento sublimatore di lucentezza.","og_url":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_mirylia_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/","url":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/","name":"Mirylia - Trattamento lucentezza | Technique","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/es\/#website"},"description":"Mirylia, trattamento sublimatore di lucentezza.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/mirylia-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tratamientos","item":"https:\/\/sandbox.technique-italia.com\/es\/categoria-prodotto\/tratamientos\/"},{"@type":"ListItem","position":3,"name":"Mirylia"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/es\/#website","url":"https:\/\/sandbox.technique-italia.com\/es\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product_cat\/1041"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/es\/wp-json\/wp\/v2\/product?product_cat=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}