{"id":585,"count":9,"description":"<img decoding=async data-opt-id=1991599174  fetchpriority=\"high\" class=\"alignnone wp-image-17668 size-full\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch_pl-1.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nBurza kolor\u00f3w dla Twoich w\u0142os\u00f3w! Croma Touch to nowy system bezpo\u015bredniej koloryzacji opracowany przez Technique, aby o\u017cywi\u0107 i roz\u015bwietli\u0107 Tw\u00f3j wygl\u0105d dzi\u0119ki 9 zaskakuj\u0105cym odcieniom: wi\u0119cej pigment\u00f3w dla pe\u0142niejszego koloru, g\u0142\u0119bokiego od\u017cywienia i zr\u00f3wnowa\u017conego refleksu.","link":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/","name":"Croma Touch","slug":"croma-touch-pl","taxonomy":"product_cat","parent":583,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maschera a colorazione diretta in 9 nuance Croma Touch<\/title>\n<meta name=\"description\" content=\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maschera a colorazione diretta in 9 nuance Croma Touch\" \/>\n<meta property=\"og:description\" content=\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/croma-touch-pl\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/croma-touch-pl\\\/\",\"name\":\"Maschera a colorazione diretta in 9 nuance Croma Touch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\"},\"description\":\"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/croma-touch-pl\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/croma-touch-pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koloryzacja\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Croma Touch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maschera a colorazione diretta in 9 nuance Croma Touch","description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/","og_locale":"pl_PL","og_type":"article","og_title":"Maschera a colorazione diretta in 9 nuance Croma Touch","og_description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","og_url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/11\/hero_colorazioni_chroma_touch-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/","url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/","name":"Maschera a colorazione diretta in 9 nuance Croma Touch","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website"},"description":"Croma Touch \u00e8 la nuova maschera a colorazione diretta ideata da Technique per ravvivare e illuminare i capelli con 9 sorprendenti nuances.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/croma-touch-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Koloryzacja","item":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/"},{"@type":"ListItem","position":3,"name":"Croma Touch"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website","url":"https:\/\/sandbox.technique-italia.com\/pl\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/583"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product?product_cat=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}