{"id":586,"count":1,"description":"<img decoding=async data-opt-id=1716992745  fetchpriority=\"high\" class=\"wp-image-15493 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_hello_cream_PL.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nJednolito\u015b\u0107 koloru i silne dzia\u0142anie kosmetyczne, dzi\u0119ki zawarto\u015bci <span style=\"font-weight: 400\">Olej bawe\u0142niany i wyci\u0105g z Orzecha w\u0142oskiego<\/span>: Hello Cream, p\u00f3\u0142trwa\u0142a koloryzacja bez amoniaku, kt\u00f3ra zapewnia d\u0142ugotrwa\u0142y, ol\u015bniewaj\u0105cy rezultat oraz naturalny efekt, kt\u00f3ry podkre\u015bla kolor, czyni\u0105c go ja\u015bniejszym i bardziej \u017cywym.","link":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/","name":"Hello Cream","slug":"hello-cream-pl","taxonomy":"product_cat","parent":583,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colorazione tono su tono semipermanente per capelli Hello Cream<\/title>\n<meta name=\"description\" content=\"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colorazione tono su tono semipermanente per capelli Hello Cream\" \/>\n<meta property=\"og:description\" content=\"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_hello_cream_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/hello-cream-pl\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/hello-cream-pl\\\/\",\"name\":\"Colorazione tono su tono semipermanente per capelli Hello Cream\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\"},\"description\":\"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/hello-cream-pl\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/hello-cream-pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koloryzacja\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hello Cream\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colorazione tono su tono semipermanente per capelli Hello Cream","description":"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/","og_locale":"pl_PL","og_type":"article","og_title":"Colorazione tono su tono semipermanente per capelli Hello Cream","og_description":"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.","og_url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_hello_cream_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/","url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/","name":"Colorazione tono su tono semipermanente per capelli Hello Cream","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website"},"description":"Hello Cream, colorazione tono su tono semipermanente per capelli, arricchita con Yogurtene e Miele. Riflessi intensi, colore duraturo.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/hello-cream-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Koloryzacja","item":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/"},{"@type":"ListItem","position":3,"name":"Hello Cream"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website","url":"https:\/\/sandbox.technique-italia.com\/pl\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/583"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product?product_cat=586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}