{"id":587,"count":1,"description":"<img decoding=async data-opt-id=2114849263  fetchpriority=\"high\" class=\"wp-image-15468 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_nuage_PL.jpg\" alt=\"\" width=\"1596\" height=\"319\" \/>\r\n\r\nPotr\u00f3jne dobroczynne dzia\u0142anie Olejku Arganowego, Oleju z Pierwiosnka i Naturalnej Keratyny \u0142\u0105cz\u0105 si\u0119 i wsp\u00f3\u0142dzia\u0142aj\u0105 w Nuage, nowej koloryzacji bez amoniaku, kt\u00f3ra zapewnia delikatne dzia\u0142anie, a tak\u017ce skuteczny i zdecydowany efekt koloryzacji.","link":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/","name":"Nuage","slug":"nuage-pl","taxonomy":"product_cat","parent":583,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colorazione permanente ad ossidazione senza ammoniaca Nuage<\/title>\n<meta name=\"description\" content=\"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colorazione permanente ad ossidazione senza ammoniaca Nuage\" \/>\n<meta property=\"og:description\" content=\"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_nuage.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/nuage-pl\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/nuage-pl\\\/\",\"name\":\"Colorazione permanente ad ossidazione senza ammoniaca Nuage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\"},\"description\":\"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/nuage-pl\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/nuage-pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koloryzacja\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/koloryzacja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colorazione permanente ad ossidazione senza ammoniaca Nuage","description":"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/","og_locale":"pl_PL","og_type":"article","og_title":"Colorazione permanente ad ossidazione senza ammoniaca Nuage","og_description":"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.","og_url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_colorazioni_nuage.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/","url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/","name":"Colorazione permanente ad ossidazione senza ammoniaca Nuage","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website"},"description":"Nuage, colorazione permanente senza ammoniaca e PPD dalla formula extra delicata e rigenerante, arricchita con Olio di Argan, Olio di Primula e Cheratina.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/nuage-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Koloryzacja","item":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/koloryzacja\/"},{"@type":"ListItem","position":3,"name":"Nuage"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website","url":"https:\/\/sandbox.technique-italia.com\/pl\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/583"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product?product_cat=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}