{"id":598,"count":58,"description":"<img decoding=async data-opt-id=795651385  fetchpriority=\"high\" class=\"wp-image-15548 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamenti_pl.jpg\" alt=\"\" width=\"1600\" height=\"350\" \/>\r\n\r\nKa\u017cde w\u0142osy potrzebuj\u0105 komfortu, pi\u0119kna i od\u017cywienia. Badania Technique pozwoli\u0142y na stworzenie kompletnej gamy zabieg\u00f3w, kt\u00f3ra zosta\u0142a opracowana po to, aby zaspokoi\u0107 potrzeby w zakresie od\u017cywienia i witalno\u015bci wszystkich rodzaj\u00f3w w\u0142os\u00f3w: suchych i ze zniszczon\u0105 struktur\u0105, zniszczonych i \u0142amliwych, kr\u0119conych, prostych, po trwa\u0142ej ondulacji i po zabiegach. Us\u0142ugi stworzone na miar\u0119 z wykorzystaniem najlepszych profesjonalnych produkt\u00f3w.","link":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/","name":"Zabiegi","slug":"zabiegi","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trattamenti professionali per capelli Technique<\/title>\n<meta name=\"description\" content=\"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trattamenti professionali per capelli Technique\" \/>\n<meta property=\"og:description\" content=\"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamenti_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/\",\"name\":\"Trattamenti professionali per capelli Technique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\"},\"description\":\"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zabiegi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trattamenti professionali per capelli Technique","description":"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/","og_locale":"pl_PL","og_type":"article","og_title":"Trattamenti professionali per capelli Technique","og_description":"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.","og_url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamenti_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/","url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/","name":"Trattamenti professionali per capelli Technique","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website"},"description":"I trattamenti professionali Technique sono ideati per soddisfare le esigenze di benessere di tutti i tipi di capelli: ricci, colorati, aridi, lisci, grassi.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Zabiegi"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website","url":"https:\/\/sandbox.technique-italia.com\/pl\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product?product_cat=598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}