{"id":599,"count":7,"description":"<img decoding=async data-opt-id=609751818  fetchpriority=\"high\" class=\"wp-image-15643 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_re-active_pl.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nKompletny zabieg dla w\u0142os\u00f3w suchych i ze zniszczon\u0105 struktur\u0105: Alkemy Re-Active uwalnia prawdziwe pi\u0119kno Twoich w\u0142os\u00f3w, dzi\u0119ki idealnemu po\u0142\u0105czeniu dobroczynnych sk\u0142adnik\u00f3w aktywnych, kt\u00f3re przywracaj\u0105 naturaln\u0105 odporno\u015b\u0107, elastyczno\u015b\u0107 oraz blask matowym i pozbawionym intensywnego koloru w\u0142osom.","link":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/","name":"Alkemy Re-Active","slug":"alkemy-reactive-pl","taxonomy":"product_cat","parent":598,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trattamento per capelli aridi e destrutturati Alkemy Re-Active<\/title>\n<meta name=\"description\" content=\"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trattamento per capelli aridi e destrutturati Alkemy Re-Active\" \/>\n<meta property=\"og:description\" content=\"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_re-active_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/alkemy-reactive-pl\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/alkemy-reactive-pl\\\/\",\"name\":\"Trattamento per capelli aridi e destrutturati Alkemy Re-Active\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\"},\"description\":\"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/alkemy-reactive-pl\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/alkemy-reactive-pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zabiegi\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/categoria-prodotto\\\/zabiegi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alkemy Re-Active\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trattamento per capelli aridi e destrutturati Alkemy Re-Active","description":"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/","og_locale":"pl_PL","og_type":"article","og_title":"Trattamento per capelli aridi e destrutturati Alkemy Re-Active","og_description":"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.","og_url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_re-active_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/","url":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/","name":"Trattamento per capelli aridi e destrutturati Alkemy Re-Active","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website"},"description":"Trattamento per capelli aridi e destrutturati: Alkemy Re-Active ripristina la naturale resistenza, elasticit\u00e0 e luminosit\u00e0 dei capelli spenti.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/alkemy-reactive-pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Zabiegi","item":"https:\/\/sandbox.technique-italia.com\/pl\/categoria-prodotto\/zabiegi\/"},{"@type":"ListItem","position":3,"name":"Alkemy Re-Active"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pl\/#website","url":"https:\/\/sandbox.technique-italia.com\/pl\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product_cat\/598"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pl\/wp-json\/wp\/v2\/product?product_cat=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}