{"id":8780,"date":"2019-03-14T16:00:41","date_gmt":"2019-03-14T15:00:41","guid":{"rendered":"https:\/\/sandbox.technique-italia.com\/\/products\/sem%20categoria\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/"},"modified":"2021-12-21T12:04:05","modified_gmt":"2021-12-21T11:04:05","slug":"alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2","status":"publish","type":"product","link":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/","title":{"rendered":"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracolados"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><b>Alkemy Curl, M\u00e1scara<\/b> <b>de defini\u00e7\u00e3o para cabelos encaracolados<\/b><span style=\"font-weight: 400;\"> e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis. F\u00f3rmula \u00e0 base de <\/span><b>extrato de moringa, <\/b><span style=\"font-weight: 400;\">com a\u00e7\u00e3o anti-inflamat\u00f3ria e calmante que potencia o <\/span><b>efeito antioxidante<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Formato de 500 ml<\/span><\/p>\n","protected":false},"featured_media":18044,"template":"","meta":[],"product_brand":[],"product_cat":[631,628],"product_tag":[],"class_list":["post-8780","product","type-product","status-publish","has-post-thumbnail","product_cat-alkemy-curl-pt-pt","product_cat-tratamentos","description-off","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv<\/title>\n<meta name=\"description\" content=\"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv\" \/>\n<meta property=\"og:description\" content=\"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-21T11:04:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2026\/03\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/\",\"name\":\"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/sandbox.technique-italia.com\\/wp-content\\/uploads\\/2026\\/03\\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp\",\"datePublished\":\"2019-03-14T15:00:41+00:00\",\"dateModified\":\"2021-12-21T11:04:05+00:00\",\"description\":\"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/#primaryimage\",\"url\":\"https:\\/\\/sandbox.technique-italia.com\\/wp-content\\/uploads\\/2026\\/03\\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp\",\"contentUrl\":\"https:\\/\\/sandbox.technique-italia.com\\/wp-content\\/uploads\\/2026\\/03\\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/products\\\/tratamentos\\\/alkemy-curl-pt-pt\\\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracolados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv","description":"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/","og_locale":"pt_PT","og_type":"article","og_title":"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv","og_description":"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.","og_url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/","og_site_name":"Technique Sandbox","article_modified_time":"2021-12-21T11:04:05+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2026\/03\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/","url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/","name":"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracoladosv","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/#primaryimage"},"image":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2026\/03\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp","datePublished":"2019-03-14T15:00:41+00:00","dateModified":"2021-12-21T11:04:05+00:00","description":"Alkemy Curl, M\u00e1scara de defini\u00e7\u00e3o para cabelos encaracolados e rebeldes. Hidrata intensamente, protege do crespo e disciplina para ondula\u00e7\u00f5es impec\u00e1veis.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/#primaryimage","url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2026\/03\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp","contentUrl":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2026\/03\/02069_technique_treatment_alkemy_curl_definition_control_mask_500ml.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/products\/tratamentos\/alkemy-curl-pt-pt\/alkemy-curl-mascara-de-definicao-para-cabelos-encaracolados-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/sandbox.technique-italia.com\/pt-pt\/shop\/"},{"@type":"ListItem","position":3,"name":"Alkemy Curl | M\u00e1scara De Defini\u00e7\u00e3o Para Cabelos Encaracolados"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/#website","url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product\/8780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/media\/18044"}],"wp:attachment":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8780"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=8780"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=8780"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=8780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}