{"id":632,"count":7,"description":"<img decoding=async data-opt-id=138929901  fetchpriority=\"high\" class=\"wp-image-15748 size-full aligncenter\" src=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_nutro_pt.jpg\" alt=\"\" width=\"1600\" height=\"320\" \/>\r\n\r\nTratamento desenvolvido para nutrir em profundidade os cabelos fortemente danificados, Alkemy Nutro atua na fibra, regenerando a estrutura gra\u00e7as \u00e0 combina\u00e7\u00e3o de princ\u00edpios ativos preciosos. Cabelos revitalizaados e regenerados tamb\u00e9m em casa, como no sal\u00e3o.","link":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/","name":"Alkemy Nutro","slug":"alkemy-nutro-pt-pt","taxonomy":"product_cat","parent":628,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trattamento nutriente per capelli danneggiati | Alkemy Nutro<\/title>\n<meta name=\"description\" content=\"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trattamento nutriente per capelli danneggiati | Alkemy Nutro\" \/>\n<meta property=\"og:description\" content=\"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/\" \/>\n<meta property=\"og:site_name\" content=\"Technique Sandbox\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_nutro_IT.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/categoria-prodotto\\\/tratamentos\\\/alkemy-nutro-pt-pt\\\/\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/categoria-prodotto\\\/tratamentos\\\/alkemy-nutro-pt-pt\\\/\",\"name\":\"Trattamento nutriente per capelli danneggiati | Alkemy Nutro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/#website\"},\"description\":\"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/categoria-prodotto\\\/tratamentos\\\/alkemy-nutro-pt-pt\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/categoria-prodotto\\\/tratamentos\\\/alkemy-nutro-pt-pt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tratamentos\",\"item\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/categoria-prodotto\\\/tratamentos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alkemy Nutro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/\",\"name\":\"Technique Sandbox\",\"description\":\"The Italian Concept\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandbox.technique-italia.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trattamento nutriente per capelli danneggiati | Alkemy Nutro","description":"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/","og_locale":"pt_PT","og_type":"article","og_title":"Trattamento nutriente per capelli danneggiati | Alkemy Nutro","og_description":"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.","og_url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/","og_site_name":"Technique Sandbox","og_image":[{"url":"https:\/\/mljhmi6yuouh.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/sandbox.technique-italia.com\/wp-content\/uploads\/2023\/10\/hero_trattamento_alkemy_nutro_IT.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/","url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/","name":"Trattamento nutriente per capelli danneggiati | Alkemy Nutro","isPartOf":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/#website"},"description":"Trattamento ideato per nutrire in profondit\u00e0 i capelli danneggiati, Alkemy Nutro rigenera la fibra grazie al connubio di ceramidi e complessi vitaminici.","breadcrumb":{"@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/alkemy-nutro-pt-pt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandbox.technique-italia.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tratamentos","item":"https:\/\/sandbox.technique-italia.com\/pt-pt\/categoria-prodotto\/tratamentos\/"},{"@type":"ListItem","position":3,"name":"Alkemy Nutro"}]},{"@type":"WebSite","@id":"https:\/\/sandbox.technique-italia.com\/pt-pt\/#website","url":"https:\/\/sandbox.technique-italia.com\/pt-pt\/","name":"Technique Sandbox","description":"The Italian Concept","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandbox.technique-italia.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/628"}],"wp:post_type":[{"href":"https:\/\/sandbox.technique-italia.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}